{"id":22424,"date":"2021-05-17T13:03:41","date_gmt":"2021-05-17T11:03:41","guid":{"rendered":"https:\/\/www.mik-ce.si\/lazienda\/il-percorso-della-mik\/"},"modified":"2021-05-17T13:03:42","modified_gmt":"2021-05-17T11:03:42","slug":"il-percorso-della-mik","status":"publish","type":"page","link":"https:\/\/www.mik-ce.si\/it\/lazienda\/il-percorso-della-mik\/","title":{"rendered":"Il percorso della MIK"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-1339299024\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"711\" height=\"400\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/vizitka-podjetja-mik-celje-1-711x400.jpg\" class=\"bg attachment-medium size-medium\" alt=\"\" \/>            \t<div class=\"video-overlay no-click fill\"><\/div>\n\t<div id=\"ytplayer-333\" class=\"ux-youtube fill object-fit hide-for-medium\" data-videoid=\"gixLyrt6oRU\" data-loop=\"1\" data-audio=\"0\"><\/div>\n                        \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-256128556\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<div class=\"video video-fit mb show-for-medium\" style=\"padding-top:56.25%;\"><p><iframe title=\"preMIK\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/gixLyrt6oRU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-256128556 {\n  width: 100%;\n}\n#text-box-256128556 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1339299024 {\n  padding-top: 56.25%;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_2071133883\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1640363031\">\n\n\t<div id=\"col-1511419568\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h1 class=\"liteHeadline\" style=\"text-align: center;\"><span style=\"font-size: 250%;\">Il percorso della MIK<\/span><\/h1>\n<h2 class=\"liteHeadline\" style=\"text-align: center;\"><span style=\"font-size: 180%;\">Una storia di visione, coraggio e successo<\/span><\/h2>\n<p style=\"text-align: center;\"><span style=\"font-size: 130%;\">Un viaggio attraverso i 30 anni di storia di uno dei pi\u00f9 grandi produttori sloveni di serramenti, MIK Celje.<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1511419568 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2071133883 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #top\" data-bullet=\"false\" data-link=\"#top\" data-title=\"top\"><a name=\"top\"><\/a><\/span>\n\n\t<section class=\"section\" id=\"section_147617767\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse row-full-width align-middle align-center\"  id=\"row-1149251206\">\n\n\t<div id=\"col-662742551\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center text-shadow-1\"  >\n\t\t\t\n\t\t\t\n<a data-animate=\"fadeInDown\" href=\"\/#1\" class=\"button secondary is-link is-small\" >\n\t\t<span>1990 \u2013 1992<\/span>\n\t<\/a>\n\n<a data-animate=\"fadeInDown\" href=\"\/#2\" class=\"button secondary is-link is-small\" >\n\t\t<span>1992 \u2013 1996<\/span>\n\t<\/a>\n\n<a data-animate=\"fadeInDown\" href=\"\/#3\" class=\"button secondary is-link is-small\" >\n\t\t<span>1996 \u2013 1997<\/span>\n\t<\/a>\n\n<a data-animate=\"fadeInDown\" href=\"\/#4\" class=\"button secondary is-link is-small\" >\n\t\t<span>1997 \u2013 1998<\/span>\n\t<\/a>\n\n<a data-animate=\"fadeInDown\" href=\"\/#5\" class=\"button secondary is-link is-small\" >\n\t\t<span>1998 \u2013 2000<\/span>\n\t<\/a>\n\n<a data-animate=\"fadeInDown\" href=\"\/#6\" class=\"button secondary is-link is-small\" >\n\t\t<span>2000 \u2013 2008<\/span>\n\t<\/a>\n\n<a data-animate=\"fadeInDown\" href=\"\/#7\" class=\"button secondary is-link is-small\" >\n\t\t<span>2007 \u2013 2010<\/span>\n\t<\/a>\n\n<a data-animate=\"fadeInDown\" href=\"\/#8\" class=\"button secondary is-link is-small\" >\n\t\t<span>2007 \u2013 danes<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<span class=\"scroll-to\" data-label=\"Scroll to: #1\" data-bullet=\"false\" data-link=\"#1\" data-title=\"1\"><a name=\"1\"><\/a><\/span>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_147617767 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_78934833\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1881866259\">\n\n\t<div id=\"col-1727075134\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\"style=\"text-align: center;\"><span style=\"color: #999; font-size: 200%;\">1990 \u2013 1992<\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">Primi passi nel garage di casa: dal parquet ai materiali per l&#8217;incorniciatura<\/span><\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1727075134 > .col-inner {\n  padding: 30px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1556385430\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>La storia dell&#8217;azienda MIK Celje inizia alla fine degli anni &#8217;80, quando un promettente e ambizioso studente di architettura, Franci Pliber\u0161ek, inizia a farsi affascinare dal mondo dell\u2019imprenditorialit\u00e0 e, dopo un percorso di studi di successo, inizia una piccola attivit\u00e0 di produzione e vendita di parquet e pavimentazioni navali. Nel 1990 trasforma questa attivit\u00e0 pomeridiana in un&#8217;azienda indipendente, che amplia la sua attivit\u00e0 importando e vendendo aste per cornici e altro materiale per l&#8217;incorniciatura. Gli esordi dell&#8217;azienda MIK Celje nel cortile di casa a Gaji, Celje. Nella casa di famiglia in cui \u00e8 cresciuto Pliber\u0161ek, la madre Marija concede al figlio l&#8217;uso di un garage in cui iniziare a realizzare i suoi sogni imprenditoriali insieme alla fidanzata di allora, Adriana, oggi moglie da numerosi anni, e ad alcuni amici.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_793312167\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"723\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-1-1992-mik-celje-1128x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-1-1992-mik-celje-1128x800.jpg 1128w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-1-1992-mik-celje-564x400.jpg 564w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-1-1992-mik-celje-768x545.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-1-1992-mik-celje-1536x1090.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-1-1992-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_793312167 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p class=\"p1\">Pliber\u0161ek stabilisce il suo primo ufficio, officina e magazzino nel garage della casa di famiglia, concessogli dalla madre Marija.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1242357167\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_456838215\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"723\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-hisa-1-1992-mik-celje-1128x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-hisa-1-1992-mik-celje-1128x800.jpg 1128w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-hisa-1-1992-mik-celje-564x400.jpg 564w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-hisa-1-1992-mik-celje-768x545.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-hisa-1-1992-mik-celje-1536x1090.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/delavnica-hisa-1-1992-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_456838215 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p class=\"p1\">La storia della MIK comincia nella casa di Franci Pliber\u0161ek a Gaji, Celje.<\/p>\n<p>Con lo sviluppo del commercio dei materiali per l&#8217;incorniciatura, iniziano anche le prime presentazioni in fiera. La MIK esordisce alla Fiera Internazionale dell&#8217;Artigianato di Celje nel 1992, dove da allora \u00e8 presente ogni anno fra i principali e ormai tradizionali espositori.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1833900967\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"723\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-1-1992-mik-celje-1128x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-1-1992-mik-celje-1128x800.jpg 1128w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-1-1992-mik-celje-564x400.jpg 564w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-1-1992-mik-celje-768x545.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-1-1992-mik-celje-1536x1090.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-1-1992-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1833900967 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_78934833 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(240, 240, 240);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_277420355\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #2\" data-bullet=\"false\" data-link=\"#2\" data-title=\"2\"><a name=\"2\"><\/a><\/span>\n<div class=\"row\"  id=\"row-1114758575\">\n\n\t<div id=\"col-1176302419\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\" style=\"text-align: center;\"><span style=\"font-size: 200%; color: #999;\">1992 \u2013 1996<\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">Incremento del commercio all&#8217;ingrosso di materiali per l&#8217;incorniciatura<\/span><\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1176302419 > .col-inner {\n  margin: 30px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1182075186\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Durante gli anni della transizione, quando nascono molte aziende minori che si occupano di incorniciatura, l&#8217;attivit\u00e0 della MIK inizia presto a fiorire e l&#8217;azienda diventa uno dei principali distributori e, in seguito, anche il pi\u00f9 grande, di materiali per l&#8217;incorniciatura nella Slovenia indipendente. In soli 3 anni di attivit\u00e0, dal \u201991 al \u201993, crea un portfolio di 200 clienti abituali, tra cui i pi\u00f9 stimati sono corniciai e galleristi sloveni. Cos\u00ec, le ambizioni e l&#8217;acuto senso degli affari di Franci Pliber\u0161ek lo spingono ad andare avanti.<\/p>\n<p class=\"p1\">Con lo sviluppo del commercio dei materiali per l&#8217;incorniciatura, iniziano anche le prime presentazioni in fiera. MIK \u00e8 un fedele espositore della Fiera internazionale dell&#8217;artigianato di Celje da quasi 30 anni.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-718381446\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_957174188\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"750\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-2-1995-mik-celje-1088x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-2-1995-mik-celje-1088x800.jpg 1088w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-2-1995-mik-celje-544x400.jpg 544w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-2-1995-mik-celje-768x565.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-2-1995-mik-celje-1536x1130.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-2-1995-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_957174188 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_277420355 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_974001910\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #3\" data-bullet=\"false\" data-link=\"#3\" data-title=\"3\"><a name=\"3\"><\/a><\/span>\n<div class=\"row\"  id=\"row-258324648\">\n\n\t<div id=\"col-343383931\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\"style=\"text-align: center;\"><span style=\"font-size: 200%; color: #999;\">1996 \u2013 1997<\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">Importazione di macchine per la produzione di finestre<\/span><\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-343383931 > .col-inner {\n  padding: 30px 0px 0px 0px;\n  margin: 0px 0px -31px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1275648301\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Franci Pliber\u0161ek comincia a importare macchine per la produzione di finestre per diversi produttori sloveni e, grazie ai contatti consolidati all&#8217;estero, promette a un conoscente di consegnargli la prima linea di produzione per finestre in Slovenia. All&#8217;epoca Franci Pliber\u0161ek che, nonostante la giovane et\u00e0, vanta gi\u00e0 un bel po&#8217; di esperienza nel commercio, sa che si tratta di un grosso affare e che non pu\u00f2 accadere dall&#8217;oggi al domani.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1507114934\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2053386736\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"655\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-mik-celje-1245x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-mik-celje-1245x800.jpg 1245w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-mik-celje-622x400.jpg 622w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-mik-celje-768x494.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-mik-celje-1536x987.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-mik-celje.jpg 1735w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2053386736 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p class=\"p1\">Prima produzione di finestre in PVC MIK nei locali di CE Plast.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_974001910 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(240, 240, 240);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1766372752\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #4\" data-bullet=\"false\" data-link=\"#4\" data-title=\"4\"><a name=\"4\"><\/a><\/span>\n<div class=\"row\"  id=\"row-1800769192\">\n\n\t<div id=\"col-1631626840\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\"style=\"text-align: center;\"><span style=\"font-size: 200%; color: #999;\">1997 \u2013 1998<\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">Quello che all&#8217;inizio sembra un fallimento si rivela, in realt\u00e0, come l&#8217;inizio della grande storia della MIK <\/span><\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1631626840 > .col-inner {\n  padding: 30px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-835581665\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Dopo alcune settimane di intenso lavoro, riesce a portare la linea di produzione promessa in Slovenia. Nel frattempo, per\u00f2, \u00e8 accaduto un imprevisto: l&#8217;attivit\u00e0 del conoscente per il quale ha acquistato e importato la linea di produzione di finestre \u00e8 fallita. Franci Pliber\u0161ek resta cos\u00ec da solo, con un debito ingente e una linea per la produzione di finestre di cui non sa che farsene. A proposito di questa storia, il direttore della MIK Celje ricorda: \u201c<em>\u00c8 stato il momento giusto per avere dubbi e un felice punto di svolta davanti al quale non ho potuto fermarmi. Ma io non credo alle coincidenze. Credo che ci sia un messaggio in ogni cosa. Se le intenzioni sono buone, ogni messaggio \u00e8 sicuramente positivo<\/em>.\u201d (dal libro Un onnipotente allo specchio, edito da Franci Pliber\u0161ek con Mateja Zorka Pav\u0161ar). \u00c8 in quel momento che acquista il capannone industriale dell&#8217;azienda fallita di Celje e, quando si trova di fronte alla linea di produzione, che non riesce a vendere a un cliente inizialmente interessato, decide di provare a costruire finestre, anche se non sa come. Franci Pliber\u0161ek inizia a realizzare le prime finestre con la moglie Adriana e alcuni fedeli colleghi in 600 m<sup>2<\/sup>, ma presto la produzione si espande a 1.700 m<sup>2<\/sup>.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1610017546\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_786870037\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"670\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-1-mik-celje-1218x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-1-mik-celje-1218x800.jpg 1218w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-1-mik-celje-609x400.jpg 609w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-1-mik-celje-768x504.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-1-mik-celje-1536x1009.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodnja-ce-plast-1-mik-celje.jpg 1753w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_786870037 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p class=\"p1\">CE Plast a Celje<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1766372752 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1371904617\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #5\" data-bullet=\"false\" data-link=\"#5\" data-title=\"5\"><a name=\"5\"><\/a><\/span>\n<div class=\"row\"  id=\"row-2051757240\">\n\n\t<div id=\"col-693321725\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\"style=\"text-align: center;\"><span style=\"font-size: 200%; color: #999;\">1998 \u2013 2000 <\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">La storia del pi\u00f9 grande produttore di serramenti in Slovenia e la sua rapida crescita <\/span><\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-693321725 > .col-inner {\n  padding: 30px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1951773065\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1652519052\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"694\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-3-1999-mik-celje-1176x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-3-1999-mik-celje-1176x800.jpg 1176w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-3-1999-mik-celje-588x400.jpg 588w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-3-1999-mik-celje-768x523.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-3-1999-mik-celje-1536x1045.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Sejem-MOS-3-1999-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1652519052 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-209318050\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_717053107\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"678\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-Gaji-mik-celje-1203x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-Gaji-mik-celje-1203x800.jpg 1203w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-Gaji-mik-celje-602x400.jpg 602w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-Gaji-mik-celje-768x511.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-Gaji-mik-celje-1536x1021.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-Gaji-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_717053107 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1866899552\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_760865933\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"765\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Racunalnisko-vodena-proizvodnja-mik-celje-1067x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Racunalnisko-vodena-proizvodnja-mik-celje-1067x800.jpg 1067w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Racunalnisko-vodena-proizvodnja-mik-celje-533x400.jpg 533w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Racunalnisko-vodena-proizvodnja-mik-celje-768x576.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Racunalnisko-vodena-proizvodnja-mik-celje-1536x1152.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Racunalnisko-vodena-proizvodnja-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_760865933 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1217562964\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Dal 1998, anno in cui MIK Celje inizia a produrre finestre in PVC, l&#8217;azienda conosce un periodo di rapida crescita. Fino al 2003, le finestre MIK vengono vendute tramite il rivenditore Merkur, e con questa mossa cresce anche il fatturato, che l&#8217;azienda investe in professionalit\u00e0, conoscenze e sviluppo, oltre che in formazione del personale. Dai primi tre dipendenti che iniziano il percorso della MIK nel garage di casa di Pliber\u0161ek, l&#8217;azienda passa a ben 30 dipendenti alla fine degli anni &#8217;90. Nel 2000, la linea di produzione si aggiorna e diventa computerizzata, uno dei primi casi in Europa. Nelle immediate vicinanze della casa in cui Franci Pliber\u0161ek ha mosso i suoi primi passi come imprenditore, MIK costruisce un nuovo palazzo di uffici e apre il suo primo salone espositivo e una galleria d&#8217;arte, in cui trovano spazio numerose mostre di artisti sloveni.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1371904617 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(240, 240, 240);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1550951494\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #6\" data-bullet=\"false\" data-link=\"#6\" data-title=\"6\"><a name=\"6\"><\/a><\/span>\n<div class=\"row\"  id=\"row-1458050323\">\n\n\t<div id=\"col-1149120780\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\" style=\"text-align: center;\"><span style=\"font-size: 200%; color: #999;\">2000 \u2013 2008 <\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">Creazione della rete di vendita e apertura dei saloni MIK<\/span><\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1149120780 > .col-inner {\n  padding: 30px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1773186267\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Una volta testato con cura il mercato sloveno attraverso la rete di vendita Merkur, tra il 2004 e il 2008 MIK inizia a espandere la propria rete di vendita al dettaglio dalla nativa Celje a tutte le regioni slovene. Segue l&#8217;apertura dei saloni di Maribor, Lubiana, Isola, Murska Sobota, Nova Gorica e, pi\u00f9 recentemente, Kranj e Novo mesto. Con l&#8217;apertura dei saloni in tutta la Slovenia, l\u2019azienda MIK intende avvicinarsi agli sloveni, che iniziano a riconoscerla e apprezzarla come produttore di serramenti di qualit\u00e0.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1971331758\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_980902204\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Otvoritev-salona-Ljubljana-mik-celje-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Otvoritev-salona-Ljubljana-mik-celje-1200x800.jpg 1200w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Otvoritev-salona-Ljubljana-mik-celje-600x400.jpg 600w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Otvoritev-salona-Ljubljana-mik-celje-768x512.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Otvoritev-salona-Ljubljana-mik-celje-1536x1024.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/Otvoritev-salona-Ljubljana-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_980902204 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1550951494 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_82173218\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #7\" data-bullet=\"false\" data-link=\"#7\" data-title=\"7\"><a name=\"7\"><\/a><\/span>\n<div class=\"row\"  id=\"row-64197125\">\n\n\t<div id=\"col-415172198\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\" style=\"text-align: center;\"><span style=\"font-size: 200%; color: #999;\">2007 \u2013 2010<\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">Quando un piccolo diventa grande, e poi ancora pi\u00f9 grande <\/span><\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-415172198 > .col-inner {\n  padding: 30px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1434082248\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1362616540\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"178\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/PanoramaGradbisca-vojnik-mik-celje-1400x244.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/PanoramaGradbisca-vojnik-mik-celje-1400x244.jpg 1400w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/PanoramaGradbisca-vojnik-mik-celje-800x139.jpg 800w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/PanoramaGradbisca-vojnik-mik-celje-768x134.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/PanoramaGradbisca-vojnik-mik-celje-1536x267.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/PanoramaGradbisca-vojnik-mik-celje-2048x356.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1362616540 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1994379494\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_110283607\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-vojnik-mik-celje-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-vojnik-mik-celje-1200x800.jpg 1200w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-vojnik-mik-celje-600x400.jpg 600w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-vojnik-mik-celje-768x512.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-vojnik-mik-celje-1536x1024.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/poslovna-stavba-vojnik-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_110283607 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1706444246\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1781993935\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"678\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-2-mik-celje-1203x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-2-mik-celje-1203x800.jpg 1203w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-2-mik-celje-602x400.jpg 602w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-2-mik-celje-768x511.jpg 768w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-2-mik-celje-1536x1021.jpg 1536w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-2-mik-celje.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1781993935 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2031619586\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_81804834\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"765\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-1-mik-celje.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-1-mik-celje.jpg 1024w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-1-mik-celje-533x400.jpg 533w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/proizvodna-hala-1-mik-celje-768x576.jpg 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_81804834 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-309734623\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Secondo il direttore e fondatore della MIK Celje, Franci Pliber\u0161ek: \u201c<em>Per un&#8217;azienda di successo non basta un punto di vista, ma un insieme di persone capaci che hanno esperienze e punti di vista diversi su come affrontare qualcosa<\/em>.\u201d Nella primavera del 2007, MIK inizia a costruire un nuovo stabilimento amministrativo e produttivo a Vojnik, completato in soli sei mesi. Quando l&#8217;azienda si trasferisce nella nuova sede a Vojnik, nel settembre 2007, il numero di dipendenti \u00e8 salito a quasi 120 e alla fine del 2010 a oltre 190 dipendenti e 110 montatori. Negli anni che seguono, nella nuova sede di Vojnik si aggiungono alla produzione di finestre in PVC anche la produzione e la vendita di serramenti in alluminio e legno e facciate ventilate, lo sviluppo e il montaggio di soluzioni complete per vetri, porte d&#8217;ingresso e porte tagliafuoco, e lo sviluppo e la produzione dei sistemi di ventilazione locale MIKrovent.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_82173218 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(240, 240, 240);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1780791964\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(153, 153, 153);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #8\" data-bullet=\"false\" data-link=\"#8\" data-title=\"8\"><a name=\"8\"><\/a><\/span>\n<div class=\"row\"  id=\"row-1954651587\">\n\n\t<div id=\"col-480442302\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"liteHeadline\" style=\"text-align: center;\"><span style=\"font-size: 200%; color: #999;\">2007 \u2013 oggi<\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 130%;\">Orientamento verso attivit\u00e0 di sviluppo scientifico &#8211; fondazione dell&#8217;Istituto del dott. Peter Novak<\/span><\/h3>\n<div class=\"row\"  id=\"row-1624809937\">\n\n\t<div id=\"col-1976012540\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;background-color:rgb(153, 153, 153);\"><\/div><\/div>\n<p>Parallelamente, MIK Celje si \u00e8 concentra anche sulle attivit\u00e0 scientifiche e di sviluppo con l&#8217;apertura dell&#8217;istituto del dott. Peter Novak e di una camera di prova, unica tra i produttori sloveni di infissi. Nella camera, simulando diverse condizioni climatiche, si eseguono test sugli elementi dei serramenti prodotti e sul sistema di ventilazione locale MIKrovent. Il tutto con l&#8217;obiettivo di sviluppare e produrre gli elementi pi\u00f9 avanzati, isolanti ed energeticamente efficienti per serramenti e sistemi di ventilazione locale. Cos\u00ec, MIK Celje aggiorna costantemente la sua attivit\u00e0 di produzione di infissi con una filosofia che ben riassume il suo slogan: \u201cMiglioriamo la qualit\u00e0 della vita\u201d.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_594305535\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"333\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/razvojni-center-prof-dr-petra-novaka-koncno.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/razvojni-center-prof-dr-petra-novaka-koncno.jpg 1000w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/razvojni-center-prof-dr-petra-novaka-koncno-800x266.jpg 800w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/05\/razvojni-center-prof-dr-petra-novaka-koncno-768x256.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_594305535 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-426986750\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1143511943\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"306\" src=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/10\/Mikrovent-35.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/10\/Mikrovent-35.jpg 1200w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/10\/Mikrovent-35-800x240.jpg 800w, https:\/\/www.mik-ce.si\/wp-content\/uploads\/2020\/10\/Mikrovent-35-768x230.jpg 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1143511943 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-480442302 > .col-inner {\n  padding: 30px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1780791964 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_186887083\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border is-dotted\"\n\t\tstyle=\"border-color:rgb(201, 201, 201);border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row\"  id=\"row-818958906\">\r\n\r\n\n\t<div id=\"col-262321556\" class=\"col small-12 large-12\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\r\n\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-262321556 > .col-inner {\n  padding: 10px 0px 0px 0px;\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_186887083 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgba(201, 201, 201, 0.1);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":22404,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-22424","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/pages\/22424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/comments?post=22424"}],"version-history":[{"count":0,"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/pages\/22424\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/pages\/22404"}],"wp:attachment":[{"href":"https:\/\/www.mik-ce.si\/it\/wp-json\/wp\/v2\/media?parent=22424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}